{"id":1115,"date":"2025-03-24T17:05:34","date_gmt":"2025-03-24T17:05:34","guid":{"rendered":"https:\/\/fanspicy.com\/insights\/?p=1115"},"modified":"2025-03-24T17:05:34","modified_gmt":"2025-03-24T17:05:34","slug":"who-owns-patreon","status":"publish","type":"post","link":"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/","title":{"rendered":"\u00bfQui\u00e9n es el propietario de Patreon? Historia y propiedad de Patreon"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#The_Founding_of_Patreon\" >La fundaci\u00f3n de Patreon<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#Jack_Contes_Motivation\" >La motivaci\u00f3n de Jack Conte<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#Collaboration_with_Sam_Yam\" >Colaboraci\u00f3n con Sam Yam<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#Platform_Development_and_Initial_Funding\" >Desarrollo de la plataforma y financiaci\u00f3n inicial<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#Impact_on_the_Creative_Community\" >Impacto en la comunidad creativa<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#Early_Funding_and_Investments\" >Financiaci\u00f3n e inversiones iniciales<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#August_2013_Initial_Funding\" >Agosto de 2013: Financiaci\u00f3n inicial<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#June_2014_Series_A_Funding\" >Junio de 2014: Financiaci\u00f3n de serie A<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#January_2016_Series_B_Funding\" >Enero de 2016: Financiaci\u00f3n de serie B<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#July_2019_Series_D_Funding\" >Julio de 2019: Financiaci\u00f3n de la serie D<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#April_2021_Series_F_Funding\" >Abril de 2021: Financiaci\u00f3n Serie F<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#Acquisitions_and_Key_Developments\" >Adquisiciones y acontecimientos clave<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#2015_Acquisition_of_Subbable\" >2015: Adquisici\u00f3n de Subbable<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#2017_Platform_Growth_and_Feature_Introductions\" >2017: Crecimiento de la plataforma e introducci\u00f3n de funciones<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#2018_Acquisition_of_Memberful\" >2018: Adquisici\u00f3n de Memberful<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#2023_Acquisition_of_Moment\" >2023: Adquisici\u00f3n de Moment<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#Ownership_and_Stakeholders\" >Propiedad y partes interesadas<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#Founders_and_Early_Ownership\" >Fundadores y primeros propietarios<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#Funding_Rounds_and_Investor_Participation\" >Rondas de financiaci\u00f3n y participaci\u00f3n de inversores<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#Recent_Challenges_and_Milestones\" >Retos e hitos recientes<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#Cybersecurity_Incident_October_2015\" >Incidente de ciberseguridad (octubre de 2015)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#Impact_of_the_COVID-19_Pandemic\" >Impacto de la pandemia de COVID-19<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#Operational_Adjustments\" >Ajustes operativos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#Product_and_Service_Innovations\" >Innovaciones en productos y servicios<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#A_Fresh_Alternative_for_Creators\" >Una nueva alternativa para los creadores<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#Why_Fanspicy_Is_the_Right_Choice_for_Creators\" >Por qu\u00e9 Fanspicy es la opci\u00f3n adecuada para los creadores<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#Conclusion\" >Conclusi\u00f3n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-28\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#FAQ\" >PREGUNTAS FRECUENTES<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-29\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#1_Who_founded_Patreon\" >1. \u00bfQui\u00e9n fund\u00f3 Patreon?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-30\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#2_Who_owns_Patreon\" >2. \u00bfA qui\u00e9n pertenece Patreon?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-31\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#3_How_did_Patreon_raise_funds\" >3. \u00bfC\u00f3mo recaud\u00f3 fondos Patreon?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-32\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#4_Has_Patreon_acquired_other_companies\" >4. \u00bfHa adquirido Patreon otras empresas?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-33\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#5_Has_Patreon_faced_any_challenges\" >5. \u00bfSe ha enfrentado Patreon a alg\u00fan reto?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-34\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#6_How_many_creators_and_patrons_use_Patreon\" >6. \u00bfCu\u00e1ntos creadores y mecenas utilizan Patreon?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-35\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#7_Has_Patreon_ever_changed_its_business_model\" >7. \u00bfHa cambiado Patreon su modelo de negocio?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-36\" href=\"https:\/\/fanspicy.com\/insights\/es\/who-owns-patreon\/#8_What_is_Patreons_future_direction\" >8. \u00bfCu\u00e1l es la direcci\u00f3n futura de Patreon?<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<p>Patreon, una de las principales plataformas de crowdfunding para creadores, se ha convertido en una herramienta clave para artistas, m\u00fasicos y otros creadores de contenidos que buscan generar ingresos directamente de sus seguidores. Sin embargo, tras su r\u00e1pido crecimiento y la evoluci\u00f3n de sus funciones, la propiedad y la estructura de Patreon han sufrido varios cambios desde su fundaci\u00f3n. Este art\u00edculo profundiza en los principales actores de Patreon, su trayectoria y los hitos significativos que han dado forma a la plataforma.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"235\" src=\"https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/02\/Patreon.png\" alt=\"\" class=\"wp-image-223\" srcset=\"https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/02\/Patreon.png 1024w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/02\/Patreon-300x69.png 300w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/02\/Patreon-768x176.png 768w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/02\/Patreon-18x4.png 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"The_Founding_of_Patreon\"><\/span>La fundaci\u00f3n de Patreon<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Patreon, creada en mayo de 2013, surgi\u00f3 de la visi\u00f3n del m\u00fasico Jack Conte y el ingeniero de software Sam Yam. La creaci\u00f3n de la plataforma se vio impulsada por la experiencia de primera mano de Conte con los retos de la monetizaci\u00f3n de contenidos digitales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Jack_Contes_Motivation\"><\/span>La motivaci\u00f3n de Jack Conte<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Jack Conte, miembro del d\u00fao musical Pomplamoose, se enfrentaba a limitaciones financieras a pesar de la popularidad de sus v\u00eddeos en YouTube. En febrero de 2013, invirti\u00f3 aproximadamente $10.000 en la producci\u00f3n de un v\u00eddeo musical de alta calidad titulado \"Pedals\". Sin embargo, los ingresos publicitarios generados por YouTube eran insuficientes para cubrir estos costes de producci\u00f3n. Consciente de que un segmento de su audiencia podr\u00eda estar dispuesto a prestar apoyo financiero, Conte imagin\u00f3 un sistema en el que los fans pudieran financiar directamente sus esfuerzos creativos de forma recurrente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Collaboration_with_Sam_Yam\"><\/span>Colaboraci\u00f3n con Sam Yam<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Para hacer realidad esta visi\u00f3n, Conte se puso en contacto con su antiguo compa\u00f1ero de Stanford, Sam Yam, que cursaba un m\u00e1ster en inform\u00e1tica. Los conocimientos t\u00e9cnicos de Yam complementaron la visi\u00f3n creativa de Conte, lo que llev\u00f3 al desarrollo de Patreon. Ambos idearon una plataforma que permit\u00eda a los aficionados, denominados \"mecenas\", realizar aportaciones econ\u00f3micas peri\u00f3dicas a sus creadores favoritos a cambio de contenidos y experiencias exclusivas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Platform_Development_and_Initial_Funding\"><\/span>Desarrollo de la plataforma y financiaci\u00f3n inicial<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>El d\u00fao dise\u00f1\u00f3 meticulosamente Patreon para tender un puente entre los creadores y su p\u00fablico, garantizando un modelo de ingresos sostenible para los artistas. En agosto de 2013, la empresa consigui\u00f3 $2,1 millones de financiaci\u00f3n de un consorcio de inversores de capital riesgo e inversores \u00e1ngeles. Esta inversi\u00f3n inicial facilit\u00f3 el crecimiento y perfeccionamiento de la plataforma. En junio de 2014, Patreon hab\u00eda recaudado otros $15 millones en una ronda de financiaci\u00f3n de serie A dirigida por Danny Rimer, de Index Ventures, lo que consolid\u00f3 a\u00fan m\u00e1s su posici\u00f3n en el mercado.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Impact_on_the_Creative_Community\"><\/span>Impacto en la comunidad creativa<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En sus primeros 18 meses, Patreon atrajo a m\u00e1s de 125.000 mecenas. A finales de 2014, la plataforma canalizaba m\u00e1s de $1 millones mensuales a creadores de contenidos, lo que subraya su importancia en la industria creativa. Este modelo permit\u00eda a los artistas centrarse en su oficio, fomentando una conexi\u00f3n m\u00e1s profunda con su p\u00fablico y garantizando la estabilidad financiera.&nbsp;<\/p>\n\n\n\n<p>La creaci\u00f3n de Patreon supuso un cambio fundamental en el panorama de los contenidos digitales, al ofrecer a los creadores una alternativa viable a los m\u00e9todos tradicionales de monetizaci\u00f3n. La colaboraci\u00f3n entre Jack Conte y Sam Yam ejemplifica c\u00f3mo la identificaci\u00f3n de una necesidad genuina, combinada con la innovaci\u00f3n t\u00e9cnica, puede dar lugar a soluciones transformadoras en el sector creativo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Early_Funding_and_Investments\"><\/span>Financiaci\u00f3n e inversiones iniciales<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Patreon, creada en mayo de 2013, experiment\u00f3 un r\u00e1pido crecimiento y consigui\u00f3 una importante financiaci\u00f3n en sus primeros a\u00f1os, lo que le permiti\u00f3 ampliar su plataforma y sus servicios.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"August_2013_Initial_Funding\"><\/span>Agosto de 2013: Financiaci\u00f3n inicial<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En agosto de 2013, Patreon recaud\u00f3 $2,1 millones en su primera ronda de financiaci\u00f3n de un grupo de inversores \u00e1ngeles y capitalistas de riesgo. Esta inversi\u00f3n inicial proporcion\u00f3 los recursos necesarios para desarrollar y mejorar la plataforma, atrayendo a m\u00e1s creadores y mecenas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"June_2014_Series_A_Funding\"><\/span>Junio de 2014: Financiaci\u00f3n de serie A<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En junio de 2014, Patreon hab\u00eda ganado una tracci\u00f3n significativa, lo que llev\u00f3 a una ronda de financiaci\u00f3n de serie A de $15 millones. Esta ronda estuvo dirigida por Danny Rimer, de Index Ventures, y cont\u00f3 con la participaci\u00f3n de otros inversores. Los fondos se destinaron a mejorar la experiencia del usuario, ampliar los esfuerzos de marketing y apoyar a la creciente comunidad de creadores y mecenas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"January_2016_Series_B_Funding\"><\/span>Enero de 2016: Financiaci\u00f3n de serie B<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En enero de 2016, Patreon consigui\u00f3 $30 millones en financiaci\u00f3n de serie B, liderada por Thrive Capital. Esta inversi\u00f3n aument\u00f3 la financiaci\u00f3n total de Patreon a $47,1 millones. Los fondos se utilizaron para seguir desarrollando la plataforma, introducir nuevas funciones y ampliar el equipo para satisfacer la creciente demanda de creadores y mecenas.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"July_2019_Series_D_Funding\"><\/span>Julio de 2019: Financiaci\u00f3n de la serie D<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Patreon continu\u00f3 su trayectoria de crecimiento y, en julio de 2019, recaud\u00f3 $60 millones en financiaci\u00f3n de Serie D. Esta ronda incluy\u00f3 inversiones de Glade Brook Capital, Thrive Capital, Index Ventures, Freestyle y notables inversores \u00e1ngeles como Serj Tankian y Hannibal Buress. Los fondos se destinaron a aumentar las capacidades de la plataforma, mejorar las herramientas para creadores y ampliar su alcance mundial.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"April_2021_Series_F_Funding\"><\/span>Abril de 2021: Financiaci\u00f3n Serie F<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En abril de 2021, Patreon anunci\u00f3 una ronda de financiaci\u00f3n de Serie F de $155 millones, lo que elev\u00f3 su valoraci\u00f3n a $4 mil millones. Liderada por Tiger Global Management, esta ronda tambi\u00e9n cont\u00f3 con la participaci\u00f3n de inversores como Woodline Partners, Wellington, Lone Pine Capital, New Enterprise Associates, DFJ Growth y Glade Brook Capital. La inversi\u00f3n se destin\u00f3 a acelerar la misi\u00f3n de Patreon de potenciar a los creadores, centr\u00e1ndose en mejorar la experiencia del usuario, ampliar las operaciones globales e introducir funciones innovadoras para apoyar a la comunidad creativa.<\/p>\n\n\n\n<p>Las primeras rondas de financiaci\u00f3n de Patreon fueron fundamentales para establecer su posici\u00f3n como plataforma l\u00edder para creadores. Cada fase de inversi\u00f3n permiti\u00f3 a la empresa innovar, expandirse y servir mejor a su comunidad, contribuyendo al vibrante ecosistema que existe hoy en d\u00eda.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Acquisitions_and_Key_Developments\"><\/span>Adquisiciones y acontecimientos clave<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Patreon ha ampliado estrat\u00e9gicamente su plataforma mediante adquisiciones y mejoras de funciones, consolidando su posici\u00f3n en la econom\u00eda de los creadores.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2015_Acquisition_of_Subbable\"><\/span>2015: Adquisici\u00f3n de Subbable<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En marzo de 2015, Patreon adquiri\u00f3 Subbable, un servicio de suscripci\u00f3n fundado por los creadores de YouTube John y Hank Green. Esta adquisici\u00f3n integr\u00f3 la base de usuarios de Subbable, incluidos creadores como CGP Grey y los canales de los hermanos Green, CrashCourse y SciShow, en el ecosistema de Patreon. Tambi\u00e9n agiliz\u00f3 los procesos de pago al consolidar los sistemas, ya que Subbable utilizaba anteriormente Amazon Payments.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2017_Platform_Growth_and_Feature_Introductions\"><\/span>2017: Crecimiento de la plataforma e introducci\u00f3n de funciones<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En mayo de 2017, Patreon hab\u00eda superado los 50.000 creadores activos y el mill\u00f3n de mecenas mensuales, con previsiones de distribuir m\u00e1s de $150 millones entre los creadores ese a\u00f1o. Para mejorar la experiencia del usuario, Patreon introdujo varias funciones.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Lente<\/strong>: Una aplicaci\u00f3n m\u00f3vil que ofrece a los creadores una plataforma para compartir fotos y v\u00eddeos, fomentando conexiones m\u00e1s estrechas con los mecenas.<br><\/li>\n\n\n\n<li><strong>Retransmisi\u00f3n en directo<\/strong>: Herramientas que permiten a los creadores organizar eventos exclusivos en directo, mejorando el compromiso en tiempo real con su audiencia.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2018_Acquisition_of_Memberful\"><\/span>2018: Adquisici\u00f3n de Memberful<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En agosto de 2018, Patreon adquiri\u00f3 Memberful, una plataforma que proporcionaba servicios de membres\u00eda que permit\u00eda a los creadores ofrecer contenido exclusivo a trav\u00e9s de sus propios sitios web. Esta adquisici\u00f3n permiti\u00f3 a Patreon ofrecer herramientas m\u00e1s s\u00f3lidas a los creadores que quer\u00edan crear sus negocios basados en membres\u00edas, atendiendo a aquellos que prefer\u00edan una soluci\u00f3n de marca blanca.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2023_Acquisition_of_Moment\"><\/span>2023: Adquisici\u00f3n de Moment<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En octubre de 2023, Patreon ampli\u00f3 su oferta con la adquisici\u00f3n de Moment, una plataforma especializada en experiencias de retransmisi\u00f3n en directo con entrada. El objetivo de esta adquisici\u00f3n era acercar a creadores y fans a trav\u00e9s de experiencias digitales memorables, mejorando las formas en que los creadores pueden monetizar sus contenidos y relacionarse con su audiencia.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/03\/pexels-belvedere-agency-1925313981-28971474-1024x683.jpg\" alt=\"\" class=\"wp-image-1116\" srcset=\"https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/03\/pexels-belvedere-agency-1925313981-28971474-1024x683.jpg 1024w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/03\/pexels-belvedere-agency-1925313981-28971474-300x200.jpg 300w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/03\/pexels-belvedere-agency-1925313981-28971474-768x512.jpg 768w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/03\/pexels-belvedere-agency-1925313981-28971474-1536x1024.jpg 1536w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/03\/pexels-belvedere-agency-1925313981-28971474-2048x1365.jpg 2048w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/03\/pexels-belvedere-agency-1925313981-28971474-18x12.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ownership_and_Stakeholders\"><\/span>Propiedad y partes interesadas<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>La estructura de propiedad de Patreon ha evolucionado a trav\u00e9s de varias rondas de financiaci\u00f3n, atrayendo importantes inversiones de empresas de capital riesgo e inversores \u00e1ngeles.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Founders_and_Early_Ownership\"><\/span>Fundadores y primeros propietarios<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Patreon fue cofundada en mayo de 2013 por Jack Conte, m\u00fasico, y Sam Yam, ingeniero de software. Ambos fundadores desempe\u00f1aron un papel fundamental en la direcci\u00f3n estrat\u00e9gica y el crecimiento de la empresa, y Conte fue su CEO.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Funding_Rounds_and_Investor_Participation\"><\/span>Rondas de financiaci\u00f3n y participaci\u00f3n de inversores<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Patreon ha pasado por m\u00faltiples rondas de financiaci\u00f3n, cada una de las cuales ha contribuido a su expansi\u00f3n y al desarrollo de la plataforma.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Serie A (junio de 2014)<\/strong>: Recaud\u00f3 $15 millones, liderados por Danny Rimer de Index Ventures.<\/li>\n\n\n\n<li><strong>Serie B (enero de 2016)<\/strong>: Asegurado $30 millones, liderado por Thrive Capital.<\/li>\n\n\n\n<li><strong>Serie C (septiembre de 2017)<\/strong>: Obtuvo $59,4 millones, tambi\u00e9n liderados por Thrive Capital.<\/li>\n\n\n\n<li><strong>Serie D (julio de 2019)<\/strong>: Recaud\u00f3 $60 millones, con la participaci\u00f3n de inversores como Glade Brook Capital.<\/li>\n\n\n\n<li><strong>Serie E (2020)<\/strong>: Consigui\u00f3 $90 millones, con inversores como Tiger Global Management.<\/li>\n\n\n\n<li><strong>Serie F (abril 2021)<\/strong>: Obtuvo $155 millones, liderados por Tiger Global Management, valorando la empresa en $4 mil millones.<\/li>\n<\/ul>\n\n\n\n<p>La estructura de propiedad de Patreon ha evolucionado significativamente a medida que la empresa atra\u00eda inversiones de diversas empresas de capital riesgo e inversores \u00e1ngeles. Inicialmente cofundada por Jack Conte y Sam Yam en 2013, la empresa ha visto c\u00f3mo su propiedad se distribu\u00eda m\u00e1s a trav\u00e9s de varias rondas de financiaci\u00f3n. Con el respaldo de empresas como Thrive Capital, Index Ventures y Tiger Global Management, Patreon recaud\u00f3 millones para impulsar su expansi\u00f3n y el desarrollo de la plataforma, alcanzando finalmente una valoraci\u00f3n de $4 mil millones en 2021.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Recent_Challenges_and_Milestones\"><\/span>Retos e hitos recientes<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Patreon ha superado diversos retos e hitos, adaptando sus estrategias para mantener su liderazgo en la econom\u00eda de los creadores.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Cybersecurity_Incident_October_2015\"><\/span>Incidente de ciberseguridad (octubre de 2015)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Patreon sufri\u00f3 una importante brecha de seguridad que expuso los datos personales, incluidas direcciones de correo electr\u00f3nico e informaci\u00f3n financiera, de millones de usuarios. La empresa respondi\u00f3 mejorando sus protocolos de seguridad para prevenir futuros incidentes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Impact_of_the_COVID-19_Pandemic\"><\/span>Impacto de la pandemia de COVID-19<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>La pandemia plante\u00f3 tanto retos como oportunidades de crecimiento para Patreon.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>2020<\/strong>: A pesar de despedir a 30 empleados debido a las presiones econ\u00f3micas, Patreon registr\u00f3 un aumento de inscripciones de creadores, ya que los artistas buscaron fuentes de ingresos alternativas durante los cierres mundiales.<\/li>\n\n\n\n<li><strong>2021<\/strong>: La empresa ampli\u00f3 su oferta, explorando integraciones con criptomonedas y NFT para ofrecer a los creadores opciones de monetizaci\u00f3n innovadoras.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Operational_Adjustments\"><\/span>Ajustes operativos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En 2022, Patreon realiz\u00f3 cambios operativos estrat\u00e9gicos.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Reducciones de plantilla<\/strong>: Despide a 80 empleados, lo que representa 17% de su plantilla, para racionalizar las operaciones y centrarse en los objetivos empresariales b\u00e1sicos.<\/li>\n\n\n\n<li><strong>Cierre de oficinas<\/strong>: Cierre de las oficinas de Dubl\u00edn y Berl\u00edn, como reflejo de un cambio estrat\u00e9gico para optimizar las operaciones globales.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Product_and_Service_Innovations\"><\/span>Innovaciones en productos y servicios<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Patreon ha innovado constantemente para mejorar la experiencia de creadores y mecenas.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Redise\u00f1o de la interfaz de usuario (octubre de 2023)<\/strong>: Introdujo una interfaz y una identidad de marca renovadas, incorporando funciones como chats comunitarios para fomentar la participaci\u00f3n.<\/li>\n\n\n\n<li><strong>Momento Adquisici\u00f3n (octubre 2023)<\/strong>: Expansi\u00f3n de la retransmisi\u00f3n en directo con pago de entradas, ofreciendo a los creadores nuevas formas de monetizar y conectar con el p\u00fablico.\u00a0<\/li>\n<\/ul>\n\n\n\n<p>La trayectoria de Patreon refleja una interacci\u00f3n din\u00e1mica de adquisiciones estrat\u00e9gicas, iniciativas de financiaci\u00f3n y respuestas adaptables a los retos del sector. Estos esfuerzos han reforzado colectivamente su compromiso de potenciar a los creadores y enriquecer el panorama de los contenidos digitales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"418\" src=\"https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2024\/12\/fanspicy_logo-1024x418.png\" alt=\"\" class=\"wp-image-13\" srcset=\"https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2024\/12\/fanspicy_logo-1024x418.png 1024w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2024\/12\/fanspicy_logo-300x123.png 300w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2024\/12\/fanspicy_logo-768x314.png 768w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2024\/12\/fanspicy_logo-1536x627.png 1536w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2024\/12\/fanspicy_logo.png 1560w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"A_Fresh_Alternative_for_Creators\"><\/span>Una nueva alternativa para los creadores<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>En el mundo en constante evoluci\u00f3n de la creaci\u00f3n de contenidos digitales, plataformas como Patreon han sentado las bases para que los creadores se ganen la vida directamente de sus fans. Sin embargo, como empresa joven e innovadora, <a href=\"https:\/\/fanspicy.com\/insights\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Fanspicy<\/a> se perfila como una alternativa atractiva: ofrece un espacio \u00fanico para que los creadores no s\u00f3lo prosperen, sino que adem\u00e1s conserven una mayor parte de sus ingresos, se relacionen directamente con su comunidad y exploren nuevas formas de monetizar sus contenidos.<\/p>\n\n\n\n<p>Mientras que Patreon sin duda ha dejado su huella en la econom\u00eda de los creadores, Fanspicy est\u00e1 dise\u00f1ada para ser una plataforma m\u00e1s flexible, que da prioridad a los creadores y se centra en maximizar las ganancias y fomentar conexiones m\u00e1s profundas. Entendemos las necesidades de los creadores y hemos adaptado nuestra plataforma para ayudarles a construir un negocio sostenible mientras tienen el control total de su contenido.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Why_Fanspicy_Is_the_Right_Choice_for_Creators\"><\/span>Por qu\u00e9 Fanspicy es la opci\u00f3n adecuada para los creadores<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Estas son algunas de las principales razones por las que Fanspicy es una alternativa interesante para los creadores que buscan una plataforma mejor para aumentar su audiencia y ganar m\u00e1s:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Generosa participaci\u00f3n en los ingresos<\/strong>: Los creadores se quedan con 80% de sus ganancias, mientras que Fanspicy s\u00f3lo cobra 20%. En el caso de los mejores creadores, la cifra desciende a\u00fan m\u00e1s: s\u00f3lo 6%, lo que te permite quedarte con 94% de tus ganancias. Este modelo garantiza que los creadores reciban una buena compensaci\u00f3n por su trabajo.<\/li>\n\n\n\n<li><strong>Diversas opciones de pago<\/strong>: Si usted prefiere PayPal, transferencias bancarias, crypto, o Paxum, Fanspicy ofrece una variedad de m\u00e9todos de pago, por lo que es f\u00e1cil de recibir sus ganancias en la forma que m\u00e1s le convenga.<\/li>\n\n\n\n<li><strong>Retransmisi\u00f3n en directo<\/strong>: Interact\u00faa directamente con tu audiencia en tiempo real. Fanspicy facilita a los creadores la organizaci\u00f3n de eventos de streaming en directo, lo que significa m\u00e1s interacci\u00f3n con tus fans y m\u00e1s oportunidades de generar ingresos.<br><strong>Comunidad mundial<\/strong>: Con nuestra funci\u00f3n de traducci\u00f3n autom\u00e1tica, los creadores pueden comunicarse sin esfuerzo con fans de todo el mundo. Puedes interactuar en tu lengua materna y tus mensajes se traducir\u00e1n para tu audiencia, rompiendo las barreras ling\u00fc\u00edsticas y permiti\u00e9ndote conectar con una base de fans diversa y global.<br><strong>F\u00e1cil integraci\u00f3n en las redes sociales<\/strong>: Fanspicy ofrece una manera f\u00e1cil para que los creadores compartan su enlace a trav\u00e9s de m\u00faltiples plataformas de medios sociales como TikTok, Instagram y Snapchat. Esto le permite hacer crecer su audiencia mientras se mantiene conectado con sus seguidores existentes.<\/li>\n\n\n\n<li><strong>Sin l\u00edmites para la creatividad<\/strong>: Tanto si te dedicas a la fotograf\u00eda, la creaci\u00f3n de v\u00eddeos, la m\u00fasica o cualquier otro campo creativo, Fanspicy te ofrece una plataforma para vender y monetizar tus creaciones sin l\u00edmites. Comparte tu arte, interact\u00faa con tus fans y convierte tu pasi\u00f3n en beneficio.<\/li>\n<\/ul>\n\n\n\n<p>Como plataforma m\u00e1s reciente, Fanspicy reconoce los retos a los que se enfrentan los creadores y se esfuerza por ofrecer una opci\u00f3n fresca y mejor para aquellos que buscan hacer crecer sus carreras e ingresos. Tanto si acabas de empezar como si ya est\u00e1s establecido en tu campo, Fanspicy te ofrece las herramientas, la comunidad y el apoyo que necesitas para triunfar.<\/p>\n\n\n\n<p><a href=\"https:\/\/fanspicy.com\/insights\/es\/signin\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00danete a nosotros<\/a> y experimenta una plataforma que realmente valora tu creatividad y trabajo duro. Fanspicy est\u00e1 aqu\u00ed para ofrecer una alternativa que se centra en capacitar a los creadores para hacer lo que aman, sin l\u00edmites y con m\u00e1s control sobre su \u00e9xito.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Conclusi\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>La estructura de propiedad de Patreon es una mezcla de inversores privados, empresas de capital riesgo y sus fundadores originales, Jack Conte y Sam Yam. A lo largo de los a\u00f1os, la empresa ha recaudado importantes fondos y ha realizado adquisiciones clave para ampliar sus servicios. Aunque sigue siendo de propiedad privada, el crecimiento y el \u00e9xito continuos de Patreon la han convertido en un actor destacado en la econom\u00eda de los creadores, con millones de mecenas activos y creadores que conf\u00edan en la plataforma.<\/p>\n\n\n\n<p>La historia de la empresa, marcada por las inversiones estrat\u00e9gicas, las adquisiciones y los retos que ha superado, muestra la evoluci\u00f3n de Patreon desde una peque\u00f1a startup hasta una plataforma global para creadores. Mientras sigue innovando, Patreon sigue siendo una herramienta vital para quienes buscan ganarse la vida con sus esfuerzos creativos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"FAQ\"><\/span>PREGUNTAS FRECUENTES<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list\">\n<div id=\"faq-question-1742832237921\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\"><span class=\"ez-toc-section\" id=\"1_Who_founded_Patreon\"><\/span>1. \u00bfQui\u00e9n fund\u00f3 Patreon?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer\">\n\n<p>Patreon fue fundada en mayo de 2013 por Jack Conte, m\u00fasico, y Sam Yam, ingeniero de software. La idea surgi\u00f3 del deseo de Conte de obtener unos ingresos sostenibles con sus v\u00eddeos de YouTube, lo que llev\u00f3 a la creaci\u00f3n de la plataforma para que los creadores recibieran apoyo directo de sus fans.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1742832243593\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\"><span class=\"ez-toc-section\" id=\"2_Who_owns_Patreon\"><\/span>2. \u00bfA qui\u00e9n pertenece Patreon?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer\">\n\n<p>Patreon es de propiedad privada, con importantes inversiones de empresas de capital riesgo como Thrive Capital e Index Ventures. La empresa fue fundada por Jack Conte y Sam Yam, que siguen siendo figuras clave de la empresa. Al tratarse de una empresa privada, la estructura de propiedad sigue sin revelarse, pero los inversores y los fundadores poseen una parte sustancial.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1742832247601\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\"><span class=\"ez-toc-section\" id=\"3_How_did_Patreon_raise_funds\"><\/span>3. \u00bfC\u00f3mo recaud\u00f3 fondos Patreon?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer\">\n\n<p>Patreon recaud\u00f3 fondos a trav\u00e9s de varias rondas de capital riesgo. Inicialmente recaud\u00f3 $2,1 millones en agosto de 2013, seguidos de una ronda de Serie A de $15 millones en junio de 2014, y $47,1 millones en financiaci\u00f3n total en 2016, con inversiones de firmas como Thrive Capital e Index Ventures.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1742832252680\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\"><span class=\"ez-toc-section\" id=\"4_Has_Patreon_acquired_other_companies\"><\/span>4. \u00bfHa adquirido Patreon otras empresas?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer\">\n\n<p>S\u00ed, Patreon ha adquirido varias empresas para ampliar su oferta. En particular, adquiri\u00f3 Subbable en 2015, que era un servicio de suscripci\u00f3n similar fundado por los hermanos Green, creadores de YouTube. En 2018, Patreon tambi\u00e9n adquiri\u00f3 Memberful, un servicio que ofrece herramientas de suscripci\u00f3n para creadores.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1742832258201\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\"><span class=\"ez-toc-section\" id=\"5_Has_Patreon_faced_any_challenges\"><\/span>5. \u00bfSe ha enfrentado Patreon a alg\u00fan reto?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer\">\n\n<p>S\u00ed, Patreon se ha enfrentado a varios retos, incluido un importante ciberataque en 2015 que expuso los datos personales de millones de usuarios. Adem\u00e1s, la empresa se enfrent\u00f3 a dificultades financieras durante la pandemia de COVID-19, lo que provoc\u00f3 despidos en 2020 y 2021. A pesar de estos retos, Patreon ha seguido creciendo.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1742832266944\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\"><span class=\"ez-toc-section\" id=\"6_How_many_creators_and_patrons_use_Patreon\"><\/span>6. \u00bfCu\u00e1ntos creadores y mecenas utilizan Patreon?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer\">\n\n<p>En 2022, Patreon contaba con m\u00e1s de 250.000 creadores y m\u00e1s de 8 millones de mecenas activos de m\u00e1s de 200 pa\u00edses. Esta cifra sigue creciendo a medida que m\u00e1s creadores recurren a la plataforma en busca de apoyo financiero y participaci\u00f3n de los fans.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1742832277856\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\"><span class=\"ez-toc-section\" id=\"7_Has_Patreon_ever_changed_its_business_model\"><\/span>7. \u00bfHa cambiado Patreon su modelo de negocio?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer\">\n\n<p>Aunque el concepto b\u00e1sico de Patreon como plataforma de suscripci\u00f3n para creadores se ha mantenido intacto, la empresa ha introducido continuamente nuevas funciones y herramientas. Entre ellas, el lanzamiento de aplicaciones m\u00f3viles como Lens, opciones de retransmisi\u00f3n en directo e incluso la exploraci\u00f3n de criptomonedas y NFT como nuevas formas de que los creadores moneticen contenidos.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1742832284257\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\"><span class=\"ez-toc-section\" id=\"8_What_is_Patreons_future_direction\"><\/span>8. \u00bfCu\u00e1l es la direcci\u00f3n futura de Patreon?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer\">\n\n<p>En 2023, Patreon anunci\u00f3 planes para redise\u00f1ar su interfaz de usuario y cambiar de marca. Adem\u00e1s, adquiri\u00f3 Moment, una plataforma de retransmisi\u00f3n en directo con pago de entradas, lo que indica su intenci\u00f3n de expandirse a\u00fan m\u00e1s en la retransmisi\u00f3n en directo y la creaci\u00f3n de contenidos basados en la comunidad. La empresa tambi\u00e9n est\u00e1 explorando el uso de criptomonedas y NFT, siguiendo el ritmo de las tendencias en la creaci\u00f3n de contenidos digitales.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\"><\/h3>","protected":false},"excerpt":{"rendered":"<p>Patreon, a leading crowdfunding platform for creators, has become a key tool for artists, musicians, and other content creators looking to generate income directly from their supporters. However, behind its rapid growth and evolving features, the ownership and structure of Patreon have undergone several changes since its founding. This article delves into the key players [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1117,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/fanspicy.com\/insights\/es\/wp-json\/wp\/v2\/posts\/1115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fanspicy.com\/insights\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fanspicy.com\/insights\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fanspicy.com\/insights\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fanspicy.com\/insights\/es\/wp-json\/wp\/v2\/comments?post=1115"}],"version-history":[{"count":1,"href":"https:\/\/fanspicy.com\/insights\/es\/wp-json\/wp\/v2\/posts\/1115\/revisions"}],"predecessor-version":[{"id":1118,"href":"https:\/\/fanspicy.com\/insights\/es\/wp-json\/wp\/v2\/posts\/1115\/revisions\/1118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fanspicy.com\/insights\/es\/wp-json\/wp\/v2\/media\/1117"}],"wp:attachment":[{"href":"https:\/\/fanspicy.com\/insights\/es\/wp-json\/wp\/v2\/media?parent=1115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fanspicy.com\/insights\/es\/wp-json\/wp\/v2\/categories?post=1115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fanspicy.com\/insights\/es\/wp-json\/wp\/v2\/tags?post=1115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}