{"id":1115,"date":"2025-03-24T17:05:34","date_gmt":"2025-03-24T17:05:34","guid":{"rendered":"https:\/\/fanspicy.com\/insights\/?p=1115"},"modified":"2025-03-24T17:05:34","modified_gmt":"2025-03-24T17:05:34","slug":"who-owns-patreon","status":"publish","type":"post","link":"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/","title":{"rendered":"Wer ist der Eigent\u00fcmer von Patreon? Verstehen Sie die Eigentumsverh\u00e4ltnisse und die Geschichte"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhalts\u00fcbersicht<\/p>\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#The_Founding_of_Patreon\" >Die Gr\u00fcndung von Patreon<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#Jack_Contes_Motivation\" >Die Motivation von Jack Conte<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#Collaboration_with_Sam_Yam\" >Zusammenarbeit mit Sam Yam<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#Platform_Development_and_Initial_Funding\" >Plattformentwicklung und Anschubfinanzierung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#Impact_on_the_Creative_Community\" >Auswirkungen auf die kreative Gemeinschaft<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#Early_Funding_and_Investments\" >Fr\u00fche Finanzierungen und Investitionen<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#August_2013_Initial_Funding\" >August 2013: Anschubfinanzierung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#June_2014_Series_A_Funding\" >Juni 2014: Serie A-Finanzierung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#January_2016_Series_B_Funding\" >Januar 2016: Serie B-Finanzierung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#July_2019_Series_D_Funding\" >Juli 2019: Finanzierung der Serie D<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#April_2021_Series_F_Funding\" >April 2021: Serie F-Finanzierung<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#Acquisitions_and_Key_Developments\" >Akquisitionen und wichtige Entwicklungen<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#2015_Acquisition_of_Subbable\" >2015: Akquisition von Subbable<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#2017_Platform_Growth_and_Feature_Introductions\" >2017: Plattformwachstum und Funktionseinf\u00fchrungen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#2018_Acquisition_of_Memberful\" >2018: Akquisition von Memberful<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#2023_Acquisition_of_Moment\" >2023: Akquisition von Moment<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#Ownership_and_Stakeholders\" >Eigentumsverh\u00e4ltnisse und Interessengruppen<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#Founders_and_Early_Ownership\" >Gr\u00fcnder und fr\u00fche Eigent\u00fcmerschaft<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#Funding_Rounds_and_Investor_Participation\" >Finanzierungsrunden und Investorenbeteiligung<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#Recent_Challenges_and_Milestones\" >J\u00fcngste Herausforderungen und Meilensteine<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#Cybersecurity_Incident_October_2015\" >Cybersicherheitsvorfall (Oktober 2015)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#Impact_of_the_COVID-19_Pandemic\" >Auswirkungen der COVID-19-Pandemie<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#Operational_Adjustments\" >Operative Anpassungen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#Product_and_Service_Innovations\" >Produkt- und Dienstleistungsinnovationen<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#A_Fresh_Alternative_for_Creators\" >Eine frische Alternative f\u00fcr Kreative<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#Why_Fanspicy_Is_the_Right_Choice_for_Creators\" >Warum Fanspicy die richtige Wahl f\u00fcr Kreative ist<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#Conclusion\" >Schlussfolgerung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-28\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#FAQ\" >FAQ<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-29\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#1_Who_founded_Patreon\" >1. Wer hat Patreon gegr\u00fcndet?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-30\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#2_Who_owns_Patreon\" >2. Wer ist Eigent\u00fcmer von Patreon?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-31\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#3_How_did_Patreon_raise_funds\" >3. Wie hat Patreon Geld gesammelt?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-32\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#4_Has_Patreon_acquired_other_companies\" >4. Hat Patreon andere Unternehmen \u00fcbernommen?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-33\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#5_Has_Patreon_faced_any_challenges\" >5. Gab es irgendwelche Herausforderungen f\u00fcr Patreon?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-34\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#6_How_many_creators_and_patrons_use_Patreon\" >6. Wie viele Macher und G\u00f6nner nutzen Patreon?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-35\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#7_Has_Patreon_ever_changed_its_business_model\" >7. Hat Patreon jemals sein Gesch\u00e4ftsmodell ge\u00e4ndert?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-36\" href=\"https:\/\/fanspicy.com\/insights\/de\/who-owns-patreon\/#8_What_is_Patreons_future_direction\" >8. Wie sieht die zuk\u00fcnftige Ausrichtung von Patreon aus?<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n\n<p>Patreon, eine f\u00fchrende Crowdfunding-Plattform f\u00fcr Kreative, hat sich zu einem wichtigen Instrument f\u00fcr K\u00fcnstler, Musiker und andere Urheber von Inhalten entwickelt, die ein Einkommen direkt von ihren Unterst\u00fctzern erzielen m\u00f6chten. Hinter dem rasanten Wachstum und den sich entwickelnden Funktionen haben sich jedoch die Eigentumsverh\u00e4ltnisse und die Struktur von Patreon seit der Gr\u00fcndung mehrfach ge\u00e4ndert. Dieser Artikel befasst sich mit den Hauptakteuren hinter Patreon, der Entwicklung der Eigentumsverh\u00e4ltnisse und wichtigen Meilensteinen, die die Plattform gepr\u00e4gt haben.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"235\" src=\"https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/02\/Patreon.png\" alt=\"\" class=\"wp-image-223\" srcset=\"https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/02\/Patreon.png 1024w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/02\/Patreon-300x69.png 300w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/02\/Patreon-768x176.png 768w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/02\/Patreon-18x4.png 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"The_Founding_of_Patreon\"><\/span>Die Gr\u00fcndung von Patreon<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Patreon wurde im Mai 2013 gegr\u00fcndet und entstand aus der Vision des Musikers Jack Conte und des Softwareentwicklers Sam Yam. Der Grund f\u00fcr die Gr\u00fcndung der Plattform waren Contes Erfahrungen aus erster Hand mit den Herausforderungen der Monetarisierung digitaler Inhalte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Jack_Contes_Motivation\"><\/span>Die Motivation von Jack Conte<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Jack Conte, Mitglied des Musikduos Pomplamoose, hatte trotz der Popularit\u00e4t seiner YouTube-Videos mit finanziellen Engp\u00e4ssen zu k\u00e4mpfen. Im Februar 2013 investierte er etwa $10.000 in die Produktion eines hochwertigen Musikvideos mit dem Titel \"Pedals\". Die von YouTube generierten Werbeeinnahmen reichten jedoch nicht aus, um diese Produktionskosten zu decken. Conte erkannte, dass ein Teil seines Publikums bereit sein k\u00f6nnte, ihn finanziell zu unterst\u00fctzen, und stellte sich ein System vor, mit dem Fans seine kreativen Bem\u00fchungen auf wiederkehrender Basis direkt finanzieren k\u00f6nnten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Collaboration_with_Sam_Yam\"><\/span>Zusammenarbeit mit Sam Yam<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Um diese Vision in die Tat umzusetzen, wandte sich Conte an seinen ehemaligen Zimmergenossen in Stanford, Sam Yam, der einen Master-Abschluss in Informatik anstrebte. Yam's technisches Fachwissen erg\u00e4nzte die kreativen Einsichten von Conte, was zur Entwicklung von Patreon f\u00fchrte. Sie konzipierten eine Plattform, die es den Fans, den so genannten \"G\u00f6nnern\", erm\u00f6glichte, ihren Lieblingsk\u00fcnstlern im Austausch f\u00fcr exklusive Inhalte und Erlebnisse regelm\u00e4\u00dfige finanzielle Beitr\u00e4ge zukommen zu lassen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Platform_Development_and_Initial_Funding\"><\/span>Plattformentwicklung und Anschubfinanzierung<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Das Duo hat Patreon sorgf\u00e4ltig entwickelt, um die Kluft zwischen K\u00fcnstlern und ihrem Publikum zu \u00fcberbr\u00fccken und ein nachhaltiges Einkommensmodell f\u00fcr K\u00fcnstler zu gew\u00e4hrleisten. Im August 2013 sicherte sich das Unternehmen eine Finanzierung in H\u00f6he von $2,1 Millionen von einem Konsortium aus Risikokapitalgebern und Angel-Investoren. Diese Anfangsinvestition erm\u00f6glichte das Wachstum und die Weiterentwicklung der Plattform. Im Juni 2014 hatte Patreon in einer Serie-A-Finanzierungsrunde unter der Leitung von Danny Rimer von Index Ventures weitere $15 Millionen eingeworben und damit seine Position auf dem Markt weiter gefestigt.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Impact_on_the_Creative_Community\"><\/span>Auswirkungen auf die kreative Gemeinschaft<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Innerhalb der ersten 18 Monate konnte Patreon \u00fcber 125.000 G\u00f6nner gewinnen. Bis Ende 2014 flossen \u00fcber die Plattform monatlich mehr als $1 Millionen an die Urheber von Inhalten, was ihre Bedeutung in der Kreativbranche unterstreicht. Dieses Modell erm\u00f6glichte es K\u00fcnstlern, sich auf ihr Handwerk zu konzentrieren, eine tiefere Verbindung zu ihrem Publikum aufzubauen und finanzielle Stabilit\u00e4t zu gew\u00e4hrleisten.&nbsp;<\/p>\n\n\n\n<p>Die Gr\u00fcndung von Patreon markierte einen entscheidenden Wandel in der Landschaft der digitalen Inhalte und bot den Urhebern eine praktikable Alternative zu den herk\u00f6mmlichen Monetarisierungsmethoden. Die Zusammenarbeit zwischen Jack Conte und Sam Yam ist ein Beispiel daf\u00fcr, wie das Erkennen eines echten Bedarfs in Kombination mit technischer Innovation zu transformativen L\u00f6sungen im Kreativsektor f\u00fchren kann.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Early_Funding_and_Investments\"><\/span>Fr\u00fche Finanzierungen und Investitionen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Patreon wurde im Mai 2013 gegr\u00fcndet, erlebte ein schnelles Wachstum und sicherte sich in den ersten Jahren eine betr\u00e4chtliche Finanzierung, die es dem Unternehmen erm\u00f6glichte, seine Plattform und Dienste zu erweitern.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"August_2013_Initial_Funding\"><\/span>August 2013: Anschubfinanzierung<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Im August 2013 erhielt Patreon in seiner ersten Finanzierungsrunde $2,1 Millionen von einer Gruppe von Angel-Investoren und Risikokapitalgebern. Diese Anfangsinvestition lieferte die notwendigen Ressourcen, um die Plattform weiterzuentwickeln und zu verbessern und mehr Sch\u00f6pfer und G\u00f6nner zu gewinnen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"June_2014_Series_A_Funding\"><\/span>Juni 2014: Serie A-Finanzierung<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Im Juni 2014 hatte Patreon eine beachtliche Zugkraft erreicht, die zu einer Finanzierungsrunde der Serie A in H\u00f6he von $15 Millionen f\u00fchrte. Diese Runde wurde von Danny Rimer von Index Ventures geleitet und umfasste auch die Beteiligung anderer Investoren. Die Gelder wurden f\u00fcr die Verbesserung der Benutzerfreundlichkeit, die Ausweitung der Marketingma\u00dfnahmen und die Unterst\u00fctzung der wachsenden Gemeinschaft von Urhebern und G\u00f6nnern verwendet.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"January_2016_Series_B_Funding\"><\/span>Januar 2016: Serie B-Finanzierung<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Im Januar 2016 sicherte sich Patreon eine Serie-B-Finanzierung in H\u00f6he von $30 Millionen, angef\u00fchrt von Thrive Capital. Mit dieser Investition erh\u00f6hte sich die Gesamtfinanzierung von Patreon auf $47,1 Millionen. Die Mittel wurden verwendet, um die Plattform weiterzuentwickeln, neue Funktionen einzuf\u00fchren und das Team zu erweitern, um die steigende Nachfrage von Urhebern und G\u00f6nnern zu bedienen.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"July_2019_Series_D_Funding\"><\/span>Juli 2019: Finanzierung der Serie D<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Patreon setzte seinen Wachstumskurs fort und sammelte im Juli 2019 $60 Millionen in einer Serie-D-Finanzierung ein. Diese Runde umfasste Investitionen von Glade Brook Capital, Thrive Capital, Index Ventures, Freestyle und namhaften Angel-Investoren wie Serj Tankian und Hannibal Buress. Die Mittel dienten dazu, die F\u00e4higkeiten der Plattform zu erweitern, die Tools f\u00fcr Kreative zu verbessern und die globale Reichweite zu vergr\u00f6\u00dfern.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"April_2021_Series_F_Funding\"><\/span>April 2021: Serie F-Finanzierung<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Im April 2021 gab Patreon eine Finanzierungsrunde der Serie F in H\u00f6he von $155 Millionen bekannt, wodurch sich die Bewertung des Unternehmens auf $4 Milliarden erh\u00f6hte. Angef\u00fchrt von Tiger Global Management beteiligten sich an dieser Runde auch Investoren wie Woodline Partners, Wellington, Lone Pine Capital, New Enterprise Associates, DFJ Growth und Glade Brook Capital. Die Investition sollte die Mission von Patreon beschleunigen, Kreative zu bef\u00e4higen. Der Schwerpunkt lag auf der Verbesserung der Benutzerfreundlichkeit, der Ausweitung der globalen Aktivit\u00e4ten und der Einf\u00fchrung innovativer Funktionen zur Unterst\u00fctzung der kreativen Community.<\/p>\n\n\n\n<p>Die ersten Finanzierungsrunden von Patreon waren ausschlaggebend f\u00fcr die Etablierung des Unternehmens als f\u00fchrende Plattform f\u00fcr Kreative. Jede Investitionsphase erm\u00f6glichte es dem Unternehmen, innovativ zu sein, zu expandieren und seine Community besser zu bedienen, was zu dem lebendigen \u00d6kosystem beitrug, das heute existiert.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Acquisitions_and_Key_Developments\"><\/span>Akquisitionen und wichtige Entwicklungen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Patreon hat seine Plattform durch \u00dcbernahmen und Funktionserweiterungen strategisch ausgebaut und damit seine Position in der Kreativwirtschaft gefestigt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2015_Acquisition_of_Subbable\"><\/span>2015: Akquisition von Subbable<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Im M\u00e4rz 2015 \u00fcbernahm Patreon Subbable, einen von den YouTube-Machern John und Hank Green gegr\u00fcndeten Abonnementdienst. Durch diese \u00dcbernahme wurde die Nutzerbasis von Subbable, darunter auch Creators wie CGP Grey und die Kan\u00e4le der Green-Br\u00fcder, CrashCourse und SciShow, in das \u00d6kosystem von Patreon integriert. Au\u00dferdem wurden die Zahlungsprozesse durch die Konsolidierung der Systeme rationalisiert, da Subbable zuvor Amazon Payments nutzte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2017_Platform_Growth_and_Feature_Introductions\"><\/span>2017: Plattformwachstum und Funktionseinf\u00fchrungen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Im Mai 2017 hatte Patreon die Marke von 50.000 aktiven Sch\u00f6pfern und einer Million monatlicher Unterst\u00fctzer \u00fcberschritten, und es wird erwartet, dass in diesem Jahr \u00fcber $150 Millionen an Sch\u00f6pfer verteilt werden. Um die Nutzererfahrung zu verbessern, f\u00fchrte Patreon mehrere Funktionen ein.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Objektiv<\/strong>: Eine mobile App, die Kreativen eine Plattform bietet, um Fotos und Videos zu teilen und so eine engere Verbindung zu ihren Kunden herzustellen.<br><\/li>\n\n\n\n<li><strong>Live-Streaming<\/strong>: Tools, mit denen Kreative exklusive Live-Events veranstalten k\u00f6nnen, um die Interaktion mit ihrem Publikum in Echtzeit zu verbessern.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2018_Acquisition_of_Memberful\"><\/span>2018: Akquisition von Memberful<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Im August 2018 \u00fcbernahm Patreon Memberful, eine Plattform, die Mitgliedschaftsdienste anbietet, mit denen Kreative exklusive Inhalte \u00fcber ihre eigenen Websites anbieten k\u00f6nnen. Diese \u00dcbernahme erm\u00f6glichte es Patreon, robustere Tools f\u00fcr Kreative anzubieten, die ihr mitgliedschaftsbasiertes Gesch\u00e4ft aufbauen wollen, und richtet sich an diejenigen, die eine White-Label-L\u00f6sung bevorzugen.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2023_Acquisition_of_Moment\"><\/span>2023: Akquisition von Moment<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Im Oktober 2023 erweiterte Patreon sein Angebot durch die \u00dcbernahme von Moment, einer Plattform, die sich auf kostenpflichtige Live-Streaming-Erlebnisse spezialisiert hat. Diese Akquisition zielte darauf ab, Urheber und Fans durch unvergessliche digitale Erlebnisse n\u00e4her zusammenzubringen und die M\u00f6glichkeiten zu verbessern, wie Urheber ihre Inhalte monetarisieren und mit ihrem Publikum in Kontakt treten k\u00f6nnen.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/03\/pexels-belvedere-agency-1925313981-28971474-1024x683.jpg\" alt=\"\" class=\"wp-image-1116\" srcset=\"https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/03\/pexels-belvedere-agency-1925313981-28971474-1024x683.jpg 1024w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/03\/pexels-belvedere-agency-1925313981-28971474-300x200.jpg 300w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/03\/pexels-belvedere-agency-1925313981-28971474-768x512.jpg 768w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/03\/pexels-belvedere-agency-1925313981-28971474-1536x1024.jpg 1536w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/03\/pexels-belvedere-agency-1925313981-28971474-2048x1365.jpg 2048w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2025\/03\/pexels-belvedere-agency-1925313981-28971474-18x12.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Ownership_and_Stakeholders\"><\/span>Eigentumsverh\u00e4ltnisse und Interessengruppen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Die Eigent\u00fcmerstruktur von Patreon hat sich durch verschiedene Finanzierungsrunden weiterentwickelt und bedeutende Investitionen von Risikokapitalfirmen und Angel-Investoren angezogen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Founders_and_Early_Ownership\"><\/span>Gr\u00fcnder und fr\u00fche Eigent\u00fcmerschaft<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Patreon wurde im Mai 2013 von Jack Conte, einem Musiker, und Sam Yam, einem Software-Ingenieur, mitbegr\u00fcndet. Beide Gr\u00fcnder spielten eine entscheidende Rolle bei der strategischen Ausrichtung und dem Wachstum des Unternehmens, wobei Conte als CEO fungierte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Funding_Rounds_and_Investor_Participation\"><\/span>Finanzierungsrunden und Investorenbeteiligung<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Patreon hat mehrere Finanzierungsrunden durchlaufen, die jeweils zur Expansion und Entwicklung der Plattform beigetragen haben.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Serie A (Juni 2014)<\/strong>: Beschaffung von $15 Millionen, angef\u00fchrt von Danny Rimer von Index Ventures.<\/li>\n\n\n\n<li><strong>Serie B (Januar 2016)<\/strong>: Sicherung von $30 Millionen, angef\u00fchrt von Thrive Capital.<\/li>\n\n\n\n<li><strong>Serie C (September 2017)<\/strong>: Erhalt von $59,4 Millionen, ebenfalls unter der F\u00fchrung von Thrive Capital.<\/li>\n\n\n\n<li><strong>Serie D (Juli 2019)<\/strong>: Aufbringung von $60 Millionen mit Beteiligung von Investoren wie Glade Brook Capital.<\/li>\n\n\n\n<li><strong>Serie E (2020)<\/strong>: Sicherstellung von $90 Millionen, mit Investoren wie Tiger Global Management.<\/li>\n\n\n\n<li><strong>Serie F (April 2021)<\/strong>: Erhalt von $155 Millionen, angef\u00fchrt von Tiger Global Management, wodurch das Unternehmen mit $4 Milliarden bewertet wurde.<\/li>\n<\/ul>\n\n\n\n<p>Die Eigent\u00fcmerstruktur von Patreon hat sich im Laufe der Zeit erheblich ver\u00e4ndert, da das Unternehmen Investitionen von verschiedenen Risikokapitalfirmen und Angel-Investoren erhalten hat. Urspr\u00fcnglich von Jack Conte und Sam Yam im Jahr 2013 mitbegr\u00fcndet, hat sich die Eigent\u00fcmerschaft des Unternehmens durch mehrere Finanzierungsrunden immer weiter verteilt. Mit der Unterst\u00fctzung von Firmen wie Thrive Capital, Index Ventures und Tiger Global Management sammelte Patreon Millionen ein, um seine Expansion und die Entwicklung der Plattform voranzutreiben und erreichte schlie\u00dflich eine Bewertung von $4 Milliarden bis 2021.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Recent_Challenges_and_Milestones\"><\/span>J\u00fcngste Herausforderungen und Meilensteine<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Patreon hat verschiedene Herausforderungen und Meilensteine gemeistert und seine Strategien angepasst, um seine F\u00fchrungsrolle in der Creator Economy zu behaupten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Cybersecurity_Incident_October_2015\"><\/span>Cybersicherheitsvorfall (Oktober 2015)<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Bei Patreon kam es zu einem schwerwiegenden Sicherheitsversto\u00df, der zur Preisgabe pers\u00f6nlicher Daten, einschlie\u00dflich E-Mail-Adressen und Finanzinformationen, von Millionen von Nutzern f\u00fchrte. Das Unternehmen reagierte, indem es seine Sicherheitsprotokolle verbesserte, um zuk\u00fcnftige Vorf\u00e4lle zu verhindern.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Impact_of_the_COVID-19_Pandemic\"><\/span>Auswirkungen der COVID-19-Pandemie<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Die Pandemie stellte Patreon sowohl vor Herausforderungen als auch vor Wachstumschancen.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>2020<\/strong>: Trotz der Entlassung von 30 Mitarbeitern aufgrund des wirtschaftlichen Drucks verzeichnete Patreon einen Anstieg der Anmeldungen von Urhebern, da K\u00fcnstler w\u00e4hrend der weltweiten Sperrungen nach alternativen Einnahmequellen suchten.<\/li>\n\n\n\n<li><strong>2021<\/strong>: Das Unternehmen erweitert sein Angebot und erforscht die Integration von Kryptow\u00e4hrungen und NFTs, um Urhebern innovative Monetarisierungsoptionen zu bieten.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Operational_Adjustments\"><\/span>Operative Anpassungen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Im Jahr 2022 nahm Patreon strategische Ver\u00e4nderungen im Betrieb vor.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Personalabbau<\/strong>: Entlassung von 80 Mitarbeitern, was 17% der Belegschaft entspricht, um den Betrieb zu rationalisieren und sich auf die Kerngesch\u00e4ftsziele zu konzentrieren.<\/li>\n\n\n\n<li><strong>B\u00fcroschlie\u00dfungen<\/strong>: Schlie\u00dfung der B\u00fcros in Dublin und Berlin als Ausdruck einer strategischen Verlagerung zur Optimierung der globalen Aktivit\u00e4ten.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Product_and_Service_Innovations\"><\/span>Produkt- und Dienstleistungsinnovationen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Patreon hat immer wieder Neuerungen eingef\u00fchrt, um die Erfahrungen von Urhebern und F\u00f6rderern zu verbessern.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Neugestaltung der Benutzeroberfl\u00e4che (Oktober 2023)<\/strong>: Einf\u00fchrung einer \u00fcberarbeiteten Benutzeroberfl\u00e4che und Markenidentit\u00e4t mit Funktionen wie Community-Chats, um das Engagement zu f\u00f6rdern.<\/li>\n\n\n\n<li><strong>Moment Acquisition (Oktober 2023)<\/strong>: Ausweitung auf kostenpflichtiges Livestreaming, das Kreativen neue M\u00f6glichkeiten zur Monetarisierung und zur Kontaktaufnahme mit dem Publikum bietet.\u00a0<\/li>\n<\/ul>\n\n\n\n<p>Die Entwicklung von Patreon ist das Ergebnis eines dynamischen Zusammenspiels von strategischen Akquisitionen, Finanzierungsinitiativen und angepassten Reaktionen auf die Herausforderungen der Branche. Diese Bem\u00fchungen haben gemeinsam das Engagement f\u00fcr die F\u00f6rderung von Urhebern und die Bereicherung der digitalen Inhaltslandschaft gest\u00e4rkt.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"418\" src=\"https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2024\/12\/fanspicy_logo-1024x418.png\" alt=\"\" class=\"wp-image-13\" srcset=\"https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2024\/12\/fanspicy_logo-1024x418.png 1024w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2024\/12\/fanspicy_logo-300x123.png 300w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2024\/12\/fanspicy_logo-768x314.png 768w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2024\/12\/fanspicy_logo-1536x627.png 1536w, https:\/\/fanspicy.com\/insights\/wp-content\/uploads\/2024\/12\/fanspicy_logo.png 1560w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"A_Fresh_Alternative_for_Creators\"><\/span>Eine frische Alternative f\u00fcr Kreative<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>In der sich st\u00e4ndig weiterentwickelnden Welt der Erstellung digitaler Inhalte haben Plattformen wie Patreon die Voraussetzungen daf\u00fcr geschaffen, dass Kreative ihren Lebensunterhalt direkt von ihren Fans bestreiten k\u00f6nnen. Doch als junges und innovatives Unternehmen, <a href=\"https:\/\/fanspicy.com\/insights\/de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Fanspicy<\/a> entwickelt sich zu einer \u00fcberzeugenden Alternative. Sie bietet Kreativen einen einzigartigen Raum, in dem sie nicht nur florieren, sondern auch einen gr\u00f6\u00dferen Teil ihrer Einnahmen behalten, sich direkt mit ihrer Community austauschen und neue Wege zur Monetarisierung ihrer Inhalte finden k\u00f6nnen.<\/p>\n\n\n\n<p>W\u00e4hrend sich Patreon in der Kreativwirtschaft einen Namen gemacht hat, ist Fanspicy eine flexiblere Plattform, bei der die Kreativen im Vordergrund stehen und der Schwerpunkt auf der Maximierung der Einnahmen und der F\u00f6rderung tieferer Verbindungen liegt. Wir verstehen die Bed\u00fcrfnisse von Kreativen und haben unsere Plattform so gestaltet, dass sie ihnen hilft, ein nachhaltiges Gesch\u00e4ft aufzubauen und dabei die volle Kontrolle \u00fcber ihre Inhalte zu behalten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Why_Fanspicy_Is_the_Right_Choice_for_Creators\"><\/span>Warum Fanspicy die richtige Wahl f\u00fcr Kreative ist<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Hier sind einige der Hauptgr\u00fcnde, warum Fanspicy eine interessante Alternative f\u00fcr Kreative ist, die nach einer besseren Plattform suchen, um ihr Publikum zu vergr\u00f6\u00dfern und mehr zu verdienen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Gro\u00dfz\u00fcgige Umsatzbeteiligung<\/strong>: Sch\u00f6pfer behalten 80% ihrer Einnahmen, wobei Fanspicy nur 20% einbeh\u00e4lt. F\u00fcr Top-Ersteller sinkt diese Zahl sogar noch weiter - nur 6% Geb\u00fchr, so dass Sie 94% Ihrer Einnahmen behalten k\u00f6nnen. Dieses Modell stellt sicher, dass die Sch\u00f6pfer f\u00fcr ihre Arbeit gut entlohnt werden.<\/li>\n\n\n\n<li><strong>Vielf\u00e4ltige Zahlungsoptionen<\/strong>: Egal, ob Sie PayPal, \u00dcberweisungen, Kryptow\u00e4hrungen oder Paxum bevorzugen, Fanspicy bietet eine Vielzahl von Auszahlungsmethoden, die es Ihnen leicht machen, Ihre Gewinne so zu erhalten, wie es Ihnen am besten passt.<\/li>\n\n\n\n<li><strong>Live-Streaming<\/strong>: Interagieren Sie direkt mit Ihrem Publikum in Echtzeit. Fanspicy macht es Kreativen leicht, Live-Streaming-Events zu veranstalten. Das bedeutet mehr Interaktion mit Ihren Fans und mehr M\u00f6glichkeiten, Einnahmen zu erzielen.<br><strong>Globale Gemeinschaft<\/strong>: Mit unserer automatischen \u00dcbersetzungsfunktion k\u00f6nnen Kreative m\u00fchelos mit Fans auf der ganzen Welt kommunizieren. Sie k\u00f6nnen in Ihrer Muttersprache interagieren, und Ihre Nachrichten werden f\u00fcr Ihr Publikum \u00fcbersetzt. So \u00fcberwinden Sie Sprachbarrieren und k\u00f6nnen sich mit einer vielf\u00e4ltigen, globalen Fangemeinde verbinden.<br><strong>Einfache Integration sozialer Medien<\/strong>: Fanspicy bietet eine einfache M\u00f6glichkeit f\u00fcr Kreative, ihren Link auf mehreren Social-Media-Plattformen wie TikTok, Instagram und Snapchat zu teilen. So k\u00f6nnen Sie Ihr Publikum vergr\u00f6\u00dfern und gleichzeitig mit Ihren bestehenden Followern in Verbindung bleiben.<\/li>\n\n\n\n<li><strong>Der Kreativit\u00e4t sind keine Grenzen gesetzt<\/strong>: Ganz gleich, ob Sie sich f\u00fcr Fotografie, Videoerstellung, Musik oder andere kreative Bereiche interessieren, Fanspicy bietet Ihnen eine Plattform, auf der Sie Ihre Kreationen ohne Grenzen verkaufen und zu Geld machen k\u00f6nnen. Teilen Sie Ihre Kunst, interagieren Sie mit Ihren Fans und verwandeln Sie Ihre Leidenschaft in Profit.<\/li>\n<\/ul>\n\n\n\n<p>Als neuere Plattform ist sich Fanspicy der Herausforderungen bewusst, mit denen Kreative konfrontiert sind, und ist bestrebt, eine neue, bessere Option f\u00fcr diejenigen anzubieten, die ihre Karriere und ihr Einkommen ausbauen m\u00f6chten. Egal, ob Sie gerade erst anfangen oder bereits in Ihrem Bereich etabliert sind, Fanspicy bietet Ihnen die Tools, die Community und die Unterst\u00fctzung, die Sie f\u00fcr Ihren Erfolg ben\u00f6tigen.<\/p>\n\n\n\n<p><a href=\"https:\/\/fanspicy.com\/insights\/de\/signin\/\" target=\"_blank\" rel=\"noreferrer noopener\">Heute mitmachen<\/a> und erleben Sie eine Plattform, die Ihre Kreativit\u00e4t und harte Arbeit wirklich zu sch\u00e4tzen wei\u00df. Fanspicy ist hier, um eine Alternative anzubieten, die sich darauf konzentriert, Kreativen die M\u00f6glichkeit zu geben, das zu tun, was sie lieben, ohne Grenzen und mit mehr Kontrolle \u00fcber ihren Erfolg.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Conclusion\"><\/span>Schlussfolgerung<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Die Eigent\u00fcmerstruktur von Patreon ist eine Mischung aus privaten Investoren, Risikokapitalfirmen und den urspr\u00fcnglichen Gr\u00fcndern Jack Conte und Sam Yam. Im Laufe der Jahre hat das Unternehmen erhebliche Mittel aufgebracht und wichtige Akquisitionen get\u00e4tigt, um seine Dienste zu erweitern. Patreon befindet sich zwar nach wie vor in Privatbesitz, aber sein kontinuierliches Wachstum und sein Erfolg haben es zu einem bedeutenden Akteur in der Kreativwirtschaft gemacht, mit Millionen von aktiven G\u00f6nnern und Kreativen, die sich auf die Plattform verlassen.<\/p>\n\n\n\n<p>Die Geschichte des Unternehmens, die von strategischen Investitionen, \u00dcbernahmen und den gemeisterten Herausforderungen gepr\u00e4gt ist, zeigt die Entwicklung von Patreon von einem kleinen Startup zu einer globalen Plattform f\u00fcr Kreative. Patreon entwickelt sich st\u00e4ndig weiter und bleibt ein wichtiges Instrument f\u00fcr alle, die ihren Lebensunterhalt mit ihrer kreativen Arbeit verdienen wollen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"FAQ\"><\/span>FAQ<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list\">\n<div id=\"faq-question-1742832237921\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\"><span class=\"ez-toc-section\" id=\"1_Who_founded_Patreon\"><\/span>1. Wer hat Patreon gegr\u00fcndet?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer\">\n\n<p>Patreon wurde im Mai 2013 von Jack Conte, einem Musiker, und Sam Yam, einem Softwareingenieur, gegr\u00fcndet. Die Idee entstand aus dem Wunsch von Conte, mit seinen YouTube-Videos ein nachhaltiges Einkommen zu erzielen, und f\u00fchrte zur Schaffung einer Plattform, auf der Kreative direkte Unterst\u00fctzung von ihren Fans erhalten k\u00f6nnen.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1742832243593\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\"><span class=\"ez-toc-section\" id=\"2_Who_owns_Patreon\"><\/span>2. Wer ist Eigent\u00fcmer von Patreon?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer\">\n\n<p>Patreon befindet sich in Privatbesitz, mit bedeutenden Investitionen von Risikokapitalfirmen wie Thrive Capital und Index Ventures. Das Unternehmen wurde von Jack Conte und Sam Yam gegr\u00fcndet, die nach wie vor Schl\u00fcsselfiguren im Unternehmen sind. Da es sich um ein privates Unternehmen handelt, werden die vollst\u00e4ndigen Eigentumsverh\u00e4ltnisse nicht bekannt gegeben, aber die Investoren und die Gr\u00fcnder halten erhebliche Anteile.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1742832247601\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\"><span class=\"ez-toc-section\" id=\"3_How_did_Patreon_raise_funds\"><\/span>3. Wie hat Patreon Geld gesammelt?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer\">\n\n<p>Patreon hat \u00fcber verschiedene Risikokapitalrunden Mittel aufgenommen. Zun\u00e4chst wurden im August 2013 $2,1 Millionen aufgebracht, gefolgt von einer Serie-A-Runde mit $15 Millionen im Juni 2014 und einer Gesamtfinanzierung von $47,1 Millionen im Jahr 2016, mit Investitionen von Firmen wie Thrive Capital und Index Ventures.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1742832252680\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\"><span class=\"ez-toc-section\" id=\"4_Has_Patreon_acquired_other_companies\"><\/span>4. Hat Patreon andere Unternehmen \u00fcbernommen?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer\">\n\n<p>Ja, Patreon hat mehrere Unternehmen \u00fcbernommen, um sein Angebot zu erweitern. Insbesondere wurde 2015 Subbable \u00fcbernommen, ein \u00e4hnlicher Abo-Dienst, der von den YouTube-Machern, den Green-Br\u00fcdern, gegr\u00fcndet wurde. Im Jahr 2018 erwarb Patreon auch Memberful, einen Dienst, der Mitgliedschafts-Tools f\u00fcr Kreative anbietet.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1742832258201\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\"><span class=\"ez-toc-section\" id=\"5_Has_Patreon_faced_any_challenges\"><\/span>5. Gab es irgendwelche Herausforderungen f\u00fcr Patreon?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer\">\n\n<p>Ja, Patreon hatte mit einigen Herausforderungen zu k\u00e4mpfen, darunter ein gro\u00dfer Cyberangriff im Jahr 2015, bei dem pers\u00f6nliche Daten von Millionen von Nutzern offengelegt wurden. Au\u00dferdem war das Unternehmen w\u00e4hrend der COVID-19-Pandemie mit finanziellen Schwierigkeiten konfrontiert, was zu Entlassungen in den Jahren 2020 und 2021 f\u00fchrte. Trotz dieser Herausforderungen ist Patreon weiter gewachsen.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1742832266944\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\"><span class=\"ez-toc-section\" id=\"6_How_many_creators_and_patrons_use_Patreon\"><\/span>6. Wie viele Macher und G\u00f6nner nutzen Patreon?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer\">\n\n<p>Im Jahr 2022 hatte Patreon \u00fcber 250.000 Sch\u00f6pfer und mehr als 8 Millionen aktive G\u00f6nner aus \u00fcber 200 L\u00e4ndern. Diese Zahl w\u00e4chst weiter, da immer mehr Kreative die Plattform f\u00fcr finanzielle Unterst\u00fctzung und Fan-Engagement nutzen.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1742832277856\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\"><span class=\"ez-toc-section\" id=\"7_Has_Patreon_ever_changed_its_business_model\"><\/span>7. Hat Patreon jemals sein Gesch\u00e4ftsmodell ge\u00e4ndert?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer\">\n\n<p>W\u00e4hrend das Kernkonzept von Patreon als abonnementbasierte Plattform f\u00fcr Kreative intakt geblieben ist, hat das Unternehmen kontinuierlich neue Funktionen und Tools eingef\u00fchrt. Dazu geh\u00f6ren die Einf\u00fchrung mobiler Apps wie Lens, Live-Streaming-Optionen und sogar die Erforschung von Kryptow\u00e4hrungen und NFTs als neue M\u00f6glichkeiten f\u00fcr Kreative, Inhalte zu monetarisieren.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1742832284257\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question\"><span class=\"ez-toc-section\" id=\"8_What_is_Patreons_future_direction\"><\/span>8. Wie sieht die zuk\u00fcnftige Ausrichtung von Patreon aus?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer\">\n\n<p>Im Jahr 2023 k\u00fcndigte Patreon Pl\u00e4ne zur Neugestaltung der Benutzeroberfl\u00e4che und zur Umbenennung an. Au\u00dferdem erwarb das Unternehmen Moment, eine Plattform f\u00fcr kostenpflichtiges Live-Streaming, und bekundete damit seine Absicht, weiter in Richtung Live-Streaming und gemeinschaftsbasierte Inhaltserstellung zu expandieren. Das Unternehmen erforscht auch die Verwendung von Kryptow\u00e4hrungen und NFTs, um mit den Trends bei der Erstellung digitaler Inhalte Schritt zu halten.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\"><\/h3>","protected":false},"excerpt":{"rendered":"<p>Patreon, a leading crowdfunding platform for creators, has become a key tool for artists, musicians, and other content creators looking to generate income directly from their supporters. However, behind its rapid growth and evolving features, the ownership and structure of Patreon have undergone several changes since its founding. This article delves into the key players [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1117,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/fanspicy.com\/insights\/de\/wp-json\/wp\/v2\/posts\/1115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fanspicy.com\/insights\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fanspicy.com\/insights\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fanspicy.com\/insights\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fanspicy.com\/insights\/de\/wp-json\/wp\/v2\/comments?post=1115"}],"version-history":[{"count":1,"href":"https:\/\/fanspicy.com\/insights\/de\/wp-json\/wp\/v2\/posts\/1115\/revisions"}],"predecessor-version":[{"id":1118,"href":"https:\/\/fanspicy.com\/insights\/de\/wp-json\/wp\/v2\/posts\/1115\/revisions\/1118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fanspicy.com\/insights\/de\/wp-json\/wp\/v2\/media\/1117"}],"wp:attachment":[{"href":"https:\/\/fanspicy.com\/insights\/de\/wp-json\/wp\/v2\/media?parent=1115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fanspicy.com\/insights\/de\/wp-json\/wp\/v2\/categories?post=1115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fanspicy.com\/insights\/de\/wp-json\/wp\/v2\/tags?post=1115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}